{"id":5697,"date":"2026-01-15T04:29:58","date_gmt":"2026-01-15T04:29:58","guid":{"rendered":"https:\/\/sexualhealth.gov.mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/"},"modified":"2026-03-23T13:41:49","modified_gmt":"2026-03-23T13:41:49","slug":"ittestjar-ghall-sti-hiv","status":"publish","type":"sexual-health-topic","link":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/","title":{"rendered":"Ittestjar g\u0127all-STI \/ HIV"},"featured_media":0,"parent":0,"menu_order":0,"template":"","sexual-category":[119,112],"class_list":["post-5697","sexual-health-topic","type-sexual-health-topic","status-publish","hentry","sexual-category-ittestjar-ghall-sti-hiv","sexual-category-sexual-health-template-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ittestjar g\u0127all-STI \/ HIV - Sexual Health Malta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ittestjar g\u0127all-STI \/ HIV - Sexual Health Malta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/\" \/>\n<meta property=\"og:site_name\" content=\"Sexual Health Malta\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T13:41:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/ittestjar-ghall-sti-hiv\\\/\",\"url\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/ittestjar-ghall-sti-hiv\\\/\",\"name\":\"Ittestjar g\u0127all-STI \\\/ HIV - Sexual Health Malta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#website\"},\"datePublished\":\"2026-01-15T04:29:58+00:00\",\"dateModified\":\"2026-03-23T13:41:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/ittestjar-ghall-sti-hiv\\\/#breadcrumb\"},\"inLanguage\":\"mlt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/ittestjar-ghall-sti-hiv\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/ittestjar-ghall-sti-hiv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/front-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ittestjar g\u0127all-STI \\\/ HIV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#website\",\"url\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/\",\"name\":\"Sexual Health Malta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"mlt\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#organization\",\"name\":\"Sexual Health Malta\",\"url\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"mlt\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/shm_logo_no_background-3.svg\",\"contentUrl\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/shm_logo_no_background-3.svg\",\"caption\":\"Sexual Health Malta\"},\"image\":{\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ittestjar g\u0127all-STI \/ HIV - Sexual Health Malta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/","og_locale":"en_US","og_type":"article","og_title":"Ittestjar g\u0127all-STI \/ HIV - Sexual Health Malta","og_url":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/","og_site_name":"Sexual Health Malta","article_modified_time":"2026-03-23T13:41:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/","url":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/","name":"Ittestjar g\u0127all-STI \/ HIV - Sexual Health Malta","isPartOf":{"@id":"https:\/\/sexualhealth.gov.mt\/#website"},"datePublished":"2026-01-15T04:29:58+00:00","dateModified":"2026-03-23T13:41:49+00:00","breadcrumb":{"@id":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/#breadcrumb"},"inLanguage":"mlt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/ittestjar-ghall-sti-hiv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sexualhealth.gov.mt\/mt\/front-page\/"},{"@type":"ListItem","position":2,"name":"Ittestjar g\u0127all-STI \/ HIV"}]},{"@type":"WebSite","@id":"https:\/\/sexualhealth.gov.mt\/#website","url":"https:\/\/sexualhealth.gov.mt\/","name":"Sexual Health Malta","description":"","publisher":{"@id":"https:\/\/sexualhealth.gov.mt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sexualhealth.gov.mt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"mlt"},{"@type":"Organization","@id":"https:\/\/sexualhealth.gov.mt\/#organization","name":"Sexual Health Malta","url":"https:\/\/sexualhealth.gov.mt\/","logo":{"@type":"ImageObject","inLanguage":"mlt","@id":"https:\/\/sexualhealth.gov.mt\/#\/schema\/logo\/image\/","url":"https:\/\/sexualhealth.gov.mt\/wp-content\/uploads\/2025\/12\/shm_logo_no_background-3.svg","contentUrl":"https:\/\/sexualhealth.gov.mt\/wp-content\/uploads\/2025\/12\/shm_logo_no_background-3.svg","caption":"Sexual Health Malta"},"image":{"@id":"https:\/\/sexualhealth.gov.mt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/sexual-health-topic\/5697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/sexual-health-topic"}],"about":[{"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/types\/sexual-health-topic"}],"wp:attachment":[{"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/media?parent=5697"}],"wp:term":[{"taxonomy":"sexual-category","embeddable":true,"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/sexual-category?post=5697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}