{"id":5712,"date":"2026-01-15T03:57:37","date_gmt":"2026-01-15T03:57:37","guid":{"rendered":"https:\/\/sexualhealth.gov.mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/"},"modified":"2026-03-23T14:15:33","modified_gmt":"2026-03-23T14:15:33","slug":"skabbja","status":"publish","type":"sexual-health-topic","link":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/","title":{"rendered":"Skabbja"},"featured_media":0,"parent":5692,"menu_order":0,"template":"","sexual-category":[112,116],"class_list":["post-5712","sexual-health-topic","type-sexual-health-topic","status-publish","hentry","sexual-category-sexual-health-template-2","sexual-category-stis-mill-a-saz-z"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Skabbja - Sexual Health Malta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skabbja - Sexual Health Malta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/\" \/>\n<meta property=\"og:site_name\" content=\"Sexual Health Malta\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T14:15:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/mard-infettiv-iehor\\\/skabbja\\\/\",\"url\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/mard-infettiv-iehor\\\/skabbja\\\/\",\"name\":\"Skabbja - Sexual Health Malta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#website\"},\"datePublished\":\"2026-01-15T03:57:37+00:00\",\"dateModified\":\"2026-03-23T14:15:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/mard-infettiv-iehor\\\/skabbja\\\/#breadcrumb\"},\"inLanguage\":\"mlt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/mard-infettiv-iehor\\\/skabbja\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/mard-infettiv-iehor\\\/skabbja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/front-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mard Infettiv Ie\u0127or\",\"item\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/mt\\\/sexual-health-topic\\\/mard-infettiv-iehor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Skabbja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#website\",\"url\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/\",\"name\":\"Sexual Health Malta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"mlt\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#organization\",\"name\":\"Sexual Health Malta\",\"url\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"mlt\",\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/shm_logo_no_background-3.svg\",\"contentUrl\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/shm_logo_no_background-3.svg\",\"caption\":\"Sexual Health Malta\"},\"image\":{\"@id\":\"https:\\\/\\\/sexualhealth.gov.mt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Skabbja - Sexual Health Malta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/","og_locale":"en_US","og_type":"article","og_title":"Skabbja - Sexual Health Malta","og_url":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/","og_site_name":"Sexual Health Malta","article_modified_time":"2026-03-23T14:15:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/","url":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/","name":"Skabbja - Sexual Health Malta","isPartOf":{"@id":"https:\/\/sexualhealth.gov.mt\/#website"},"datePublished":"2026-01-15T03:57:37+00:00","dateModified":"2026-03-23T14:15:33+00:00","breadcrumb":{"@id":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/#breadcrumb"},"inLanguage":"mlt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/skabbja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sexualhealth.gov.mt\/mt\/front-page\/"},{"@type":"ListItem","position":2,"name":"Mard Infettiv Ie\u0127or","item":"https:\/\/sexualhealth.gov.mt\/mt\/sexual-health-topic\/mard-infettiv-iehor\/"},{"@type":"ListItem","position":3,"name":"Skabbja"}]},{"@type":"WebSite","@id":"https:\/\/sexualhealth.gov.mt\/#website","url":"https:\/\/sexualhealth.gov.mt\/","name":"Sexual Health Malta","description":"","publisher":{"@id":"https:\/\/sexualhealth.gov.mt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sexualhealth.gov.mt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"mlt"},{"@type":"Organization","@id":"https:\/\/sexualhealth.gov.mt\/#organization","name":"Sexual Health Malta","url":"https:\/\/sexualhealth.gov.mt\/","logo":{"@type":"ImageObject","inLanguage":"mlt","@id":"https:\/\/sexualhealth.gov.mt\/#\/schema\/logo\/image\/","url":"https:\/\/sexualhealth.gov.mt\/wp-content\/uploads\/2025\/12\/shm_logo_no_background-3.svg","contentUrl":"https:\/\/sexualhealth.gov.mt\/wp-content\/uploads\/2025\/12\/shm_logo_no_background-3.svg","caption":"Sexual Health Malta"},"image":{"@id":"https:\/\/sexualhealth.gov.mt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/sexual-health-topic\/5712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/sexual-health-topic"}],"about":[{"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/types\/sexual-health-topic"}],"up":[{"embeddable":true,"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/sexual-health-topic\/5692"}],"wp:attachment":[{"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/media?parent=5712"}],"wp:term":[{"taxonomy":"sexual-category","embeddable":true,"href":"https:\/\/sexualhealth.gov.mt\/mt\/wp-json\/wp\/v2\/sexual-category?post=5712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}